{"id":5516,"date":"2021-10-06T16:48:57","date_gmt":"2021-10-06T19:48:57","guid":{"rendered":"https:\/\/www.ufmg.br\/dti\/?page_id=5516"},"modified":"2026-07-28T09:43:08","modified_gmt":"2026-07-28T12:43:08","slug":"escritorio-de-projetos","status":"publish","type":"page","link":"https:\/\/www.ufmg.br\/dti\/escritorio-de-projetos\/","title":{"rendered":"Escrit\u00f3rio de Projetos"},"content":{"rendered":"<p align=\"justify\">Um escrit\u00f3rio de projetos \u00e9 <i>\u201cum corpo ou entidade organizacional \u00e0 qual s\u00e3o atribu\u00eddas v\u00e1rias responsabilidades relacionadas ao gerenciamento centralizado e coordenado dos projetos sob seu dom\u00ednio.<!--more--> As responsabilidades [&#8230;] podem variar desde fornecer fun\u00e7\u00f5es de suporte ao gerenciamento de projetos at\u00e9 ser respons\u00e1vel pelo gerenciamento direto de um projeto.\u201d<\/i> (PMBOK, 2018)<\/p>\n<p align=\"justify\">A universidade \u00e9 uma organiza\u00e7\u00e3o din\u00e2mica em cont\u00ednua transforma\u00e7\u00e3o, sendo os seus recursos humanos e or\u00e7ament\u00e1rios finitos e limitados de acordo com o contexto e a disponibilidade. Tendo em vista a constante e alta demanda por projetos de TIC, a DTI tra\u00e7a objetivos, estrat\u00e9gias, metas e indicadores que direcionam suas a\u00e7\u00f5es. Dessa forma, \u00e9 essencial a exist\u00eancia de um processo para viabilizar a realiza\u00e7\u00e3o de projetos de TIC que sejam coerentes com os objetivos estrat\u00e9gicos organizacionais. <\/p>\n<div style=\" width: 80%; margin-left: 20%;\">\n<p align=\"justify\">\u201c<i>O gerenciamento de portf\u00f3lios se concentra em garantir que os projetos e programas sejam analisados a fim de priorizar a aloca\u00e7\u00e3o de recursos e que sejam consistentes e integrados \u00e0s estrat\u00e9gias organizacionais.\u201d <\/i>(Metodologia de Gerenciamento de Portf\u00f3lio de Projetos, SISP, 2013)<\/p>\n<\/div>\n<p align=\"justify\">O gerenciamento do portf\u00f3lio deve tamb\u00e9m disciplinar demandas intempestivas, de forma minimamente ordenada, atuando no seu planejamento e prioriza\u00e7\u00e3o. Esse processo est\u00e1 sob a responsabilidade do Escrit\u00f3rio de Projetos.<\/p>\n<p align=\"justify\">O Escrit\u00f3rio de Projetos (EP) da DTI gere o Portf\u00f3lio de Projetos conforme o processo descrito na metodologia citada anteriormente, a partir das prioriza\u00e7\u00f5es feitas nos referidos comit\u00eas, do interesse da Administra\u00e7\u00e3o, das adapta\u00e7\u00f5es necess\u00e1rias e das orienta\u00e7\u00f5es advindas de reuni\u00f5es de acompanhamento e de planejamento de projetos. As demandas de projetos devem ser formalizadas atrav\u00e9s do <a href=\"https:\/\/www.ufmg.br\/dti\/servicos\/#projetossolicitacaodeprojeto\">Servi\u00e7o de Solicita\u00e7\u00e3o de Projeto<\/a> dispon\u00edvel no cat\u00e1logo da DTI.<\/p>\n<p align=\"justify\">Demais atividades do escrit\u00f3rio de projetos:<\/p>\n<ul>\n<li>\n<p align=\"justify\">Apoio \u00e0 alta administra\u00e7\u00e3o por meio do fornecimento de informa\u00e7\u00f5es sobre o andamento dos projetos;<\/p>\n<\/li>\n<li>\n<p align=\"justify\">Identifica\u00e7\u00e3o e desenvolvimento de metodologia, melhores pr\u00e1ticas, normas, modelos e outras documenta\u00e7\u00f5es para o gerenciamento de projetos;<\/p>\n<\/li>\n<li>\n<p align=\"justify\">Suporte aos gerentes de projeto por meio de consultoria e assessoramento no desenvolvimento dos projetos;<\/p>\n<\/li>\n<li>\n<p align=\"justify\">Treinamento no uso da metodologia de gerenciamento de projetos; e<\/p>\n<\/li>\n<li>\n<p align=\"justify\">Assegurar que os projetos sigam a metodologia definida.<\/p>\n<\/li>\n<\/ul>\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"coauthors":[79],"class_list":["post-5516","page","type-page","status-publish"],"_links":{"self":[{"href":"https:\/\/www.ufmg.br\/dti\/wp-json\/wp\/v2\/pages\/5516","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ufmg.br\/dti\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ufmg.br\/dti\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ufmg.br\/dti\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ufmg.br\/dti\/wp-json\/wp\/v2\/comments?post=5516"}],"version-history":[{"count":1,"href":"https:\/\/www.ufmg.br\/dti\/wp-json\/wp\/v2\/pages\/5516\/revisions"}],"predecessor-version":[{"id":8871,"href":"https:\/\/www.ufmg.br\/dti\/wp-json\/wp\/v2\/pages\/5516\/revisions\/8871"}],"wp:attachment":[{"href":"https:\/\/www.ufmg.br\/dti\/wp-json\/wp\/v2\/media?parent=5516"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/www.ufmg.br\/dti\/wp-json\/wp\/v2\/coauthors?post=5516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}