{"id":5266,"date":"2024-07-10T11:37:39","date_gmt":"2024-07-10T14:37:39","guid":{"rendered":"https:\/\/www.ufmg.br\/ieat\/?page_id=5266"},"modified":"2024-07-10T14:19:45","modified_gmt":"2024-07-10T17:19:45","slug":"mesa-redonda-potencial-e-o-modelo-de-exploracao-do-pre-sal","status":"publish","type":"page","link":"https:\/\/www.ufmg.br\/ieat\/eventos\/mesa-redonda-potencial-e-o-modelo-de-exploracao-do-pre-sal\/","title":{"rendered":"Mesa-redonda Potencial e o modelo de explora\u00e7\u00e3o do pr\u00e9-sal"},"content":{"rendered":"<p><strong>Data:<\/strong>\u00a015 de setembro de 2017<br \/>\n<strong>Local:<\/strong>\u00a0Faculdade de Ci\u00eancias Econ\u00f4micas da UFMG.<\/p>\n<p>A mesa-redonda, que reune especialistas no assunto, traz para a UFMG a discuss\u00e3o sobre o futuro e presente da explora\u00e7\u00e3o das jazidas de petr\u00f3leo do pr\u00e9-sal, visto com potencial de revolucionar a economia brasileira. Atualmente j\u00e1 s\u00e3o extra\u00eddos mais de um milh\u00e3o de barris de petr\u00f3leo no pa\u00eds do pr\u00e9-sal, e o programa, dimensionado para alavancar o desenvolvimento cient\u00edfico e tecnol\u00f3gico do pa\u00eds, \u00e9 motivo de interesses econ\u00f4micos os mais diversos e \u00e0s vezes inconfess\u00e1veis. As regras para concess\u00f5es de explora\u00e7\u00e3o, a pol\u00edtica de conte\u00fado local e o destino dos recursos obtidos s\u00e3o temas urgentes e estranhamente pouco discutidos na imprensa. Os desafios cient\u00edficos e tecnol\u00f3gicos se apresentam como uma oportunidade sem paralelo para as universidades e institutos de pesquisa brasileiros.<\/p>\n<p><strong>Sobre os convidados<br \/>\n<\/strong>Guilherme Estrella, ex-diretor de explora\u00e7\u00e3o da Petrobras e ator importante da constru\u00e7\u00e3o e consolida\u00e7\u00e3o das estrat\u00e9gias de explora\u00e7\u00e3o das jazidas, Klaus Dalgaard, professor de ci\u00eancias pol\u00edticas da UFMG e especialista em pol\u00edticas energ\u00e9ticas, e Cl\u00e1udio Scliar, professor aposentado do Instituto de Geoci\u00eancias da UFMG e antigo secret\u00e1rio de Geologia do Minist\u00e9rio de Minas e Energia.<\/p>\n<style>#sp-ea-5265 .spcollapsing { height: 0; overflow: hidden; transition-property: height;transition-duration: 500ms;}#sp-ea-5265.sp-easy-accordion>.sp-ea-single {margin-bottom: 10px; border: 1px solid #e2e2e2; }#sp-ea-5265.sp-easy-accordion>.sp-ea-single>.ea-header a {color: #444;}#sp-ea-5265.sp-easy-accordion>.sp-ea-single>.sp-collapse>.ea-body {background: #fff; color: #444;}#sp-ea-5265.sp-easy-accordion>.sp-ea-single {background: #eee;}#sp-ea-5265.sp-easy-accordion>.sp-ea-single>.ea-header a .ea-expand-icon { float: left; color: #444;font-size: 16px;}<\/style><div id=\"sp_easy_accordion-1788351935\"><div id=\"sp-ea-5265\" class=\"sp-ea-one sp-easy-accordion\" data-ea-active=\"ea-click\" data-ea-mode=\"vertical\" data-preloader=\"\" data-scroll-active-item=\"\" data-offset-to-scroll=\"0\"><div class=\"ea-card ea-expand sp-ea-single\"><h3 class=\"ea-header\"><a class=\"collapsed\" id=\"ea-header-52650\" role=\"button\" data-sptoggle=\"spcollapse\" data-sptarget=\"#collapse52650\" aria-controls=\"collapse52650\" href=\"#\" aria-expanded=\"true\" tabindex=\"0\"><i aria-hidden=\"true\" role=\"presentation\" class=\"ea-expand-icon eap-icon-ea-expand-minus\"><\/i> V\u00eddeo<\/a><\/h3><div class=\"sp-collapse spcollapse collapsed show\" id=\"collapse52650\" data-parent=\"#sp-ea-5265\" role=\"region\" aria-labelledby=\"ea-header-52650\"> <div class=\"ea-body\"><p><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/G4xe4T0E0eU?si=_-BJnITjnu7Lgm0T\" title=\"YouTube video player\" frameborder=\"0\" allowfullscreen><\/iframe><\/p><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Data:\u00a015 de setembro de 2017 Local:\u00a0Faculdade de Ci\u00eancias Econ\u00f4micas da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":381,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5266","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ufmg.br\/ieat\/wp-json\/wp\/v2\/pages\/5266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ufmg.br\/ieat\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ufmg.br\/ieat\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ufmg.br\/ieat\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ufmg.br\/ieat\/wp-json\/wp\/v2\/comments?post=5266"}],"version-history":[{"count":1,"href":"https:\/\/www.ufmg.br\/ieat\/wp-json\/wp\/v2\/pages\/5266\/revisions"}],"predecessor-version":[{"id":5267,"href":"https:\/\/www.ufmg.br\/ieat\/wp-json\/wp\/v2\/pages\/5266\/revisions\/5267"}],"up":[{"embeddable":true,"href":"https:\/\/www.ufmg.br\/ieat\/wp-json\/wp\/v2\/pages\/381"}],"wp:attachment":[{"href":"https:\/\/www.ufmg.br\/ieat\/wp-json\/wp\/v2\/media?parent=5266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}