﻿{"id":1735,"date":"2021-08-16T00:35:46","date_gmt":"2021-08-16T03:35:46","guid":{"rendered":"https:\/\/www.ufmg.br\/pginovacaotecnologica\/?p=1735"},"modified":"2021-08-17T22:07:42","modified_gmt":"2021-08-18T01:07:42","slug":"nova-eleicao-de-membros-docentes-do-colegiado-do-ppgit","status":"publish","type":"post","link":"https:\/\/www.ufmg.br\/pginovacaotecnologica\/index.php\/2021\/08\/16\/nova-eleicao-de-membros-docentes-do-colegiado-do-ppgit\/","title":{"rendered":"Nova elei\u00e7\u00e3o de membros docentes do colegiado do PPGIT"},"content":{"rendered":"<p><b>Nova elei\u00e7\u00e3o de membros docentes do colegiado do PPGIT, conforme orienta\u00e7\u00f5es do edital postando neste post.<\/b><\/p>\n<p><!--more--><\/p>\n<p>A Coordena\u00e7\u00e3o do Programa de P\u00f3s-Gradua\u00e7\u00e3o em Inova\u00e7\u00e3o Tecnol\u00f3gica \u2013 PPGIT UFMG, no uso de suas atribui\u00e7\u00f5es, torna p\u00fablico <strong>o edital para a composi\u00e7\u00e3o dos novos membros docentes do colegiado do PPGIT. <\/strong>Informamos que, por problemas de ordem t\u00e9cnica, a elei\u00e7\u00e3o de membros docentes do colegiado do PPGIT, n\u00e3o p\u00f4de ser realizada no dia marcado anteriormente (26\/07).<\/p>\n<p>Foi publicado novo edital modificando a <strong>data da elei\u00e7\u00e3o para o dia 18 de agosto de 2021 de 08h00 \u00e0s 17h00<\/strong> atrav\u00e9s do portal Minha UFMG &gt; Consultas eleitorais (<a href=\"https:\/\/sistemas.ufmg.br\/consultaseleitorais\/voto\/telaConsultarVotos.jsf\">https:\/\/sistemas.ufmg.br\/consultaseleitorais\/voto\/telaConsultarVotos.jsf<\/a>)<\/p>\n<p>Divulga\u00e7\u00e3o das chapas dos candidatos \u00e0 membros do Colegiado do PPGITB:<\/p>\n<p><strong>TITULAR\u00a0 \u00a0<\/strong>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 <strong>\u00a0 SUPLENTE<\/strong><\/p>\n<p>1- Ado J\u00f3rio de Vasconcelos\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Allan Claudius Queiroz Barbosa<br \/>\n2- Fabr\u00edcio Bertini Pasquot Polido\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Francisco Vidal Barbosa<br \/>\n3- Maria Esperanza Cortes Segura\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Virg\u00ednia Soares Lemos<br \/>\n4- Rub\u00e9n Dario Sinisterra\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Maria Jos\u00e9 Campagnole Santos<br \/>\n5- Frederic Frezard\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Carlos Alberto Tagliati<br \/>\n6- Elaine Maria de Souza Fagundes\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0Adriana Abalen Martins Dias<br \/>\n7- Renata Sim\u00f5es Guimar\u00e3es e Borges\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Eduardo de Campos Valadares<\/p>\n<p>Para mais informa\u00e7\u00f5es (<a href=\"https:\/\/www.ufmg.br\/pginovacaotecnologica\/wp-content\/uploads\/2021\/08\/SEI_UFMG-0890181-Edital.pdf\">clique aqui<\/a>)<\/p>\n<p><strong>Dia:<\/strong> 18\/08\/2021<br \/>\n<strong>Hor\u00e1rio:<\/strong> 08:00 hs \u00e0s 17:00 hs.<br \/>\n<strong>Link:<\/strong> <a href=\"https:\/\/sistemas.ufmg.br\/consultaseleitorais\/index.jsf_\">https:\/\/sistemas.ufmg.br\/consultaseleitorais\/index.jsf_<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nova elei\u00e7\u00e3o de membros docentes do colegiado do PPGIT, conforme orienta\u00e7\u00f5es do edital postando neste post.<\/p>\n","protected":false},"author":4,"featured_media":1737,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_price":"","_stock":"","_tribe_ticket_header":"","_tribe_default_ticket_provider":"","_tribe_ticket_capacity":"0","_ticket_start_date":"","_ticket_end_date":"","_tribe_ticket_show_description":"","_tribe_ticket_show_not_going":false,"_tribe_ticket_use_global_stock":"","_tribe_ticket_global_stock_level":"","_global_stock_mode":"","_global_stock_cap":"","_tribe_rsvp_for_event":"","_tribe_ticket_going_count":"","_tribe_ticket_not_going_count":"","_tribe_tickets_list":"[]","_tribe_ticket_has_attendee_info_fields":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1735","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.ufmg.br\/pginovacaotecnologica\/index.php\/wp-json\/wp\/v2\/posts\/1735","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ufmg.br\/pginovacaotecnologica\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ufmg.br\/pginovacaotecnologica\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ufmg.br\/pginovacaotecnologica\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ufmg.br\/pginovacaotecnologica\/index.php\/wp-json\/wp\/v2\/comments?post=1735"}],"version-history":[{"count":7,"href":"https:\/\/www.ufmg.br\/pginovacaotecnologica\/index.php\/wp-json\/wp\/v2\/posts\/1735\/revisions"}],"predecessor-version":[{"id":1752,"href":"https:\/\/www.ufmg.br\/pginovacaotecnologica\/index.php\/wp-json\/wp\/v2\/posts\/1735\/revisions\/1752"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ufmg.br\/pginovacaotecnologica\/index.php\/wp-json\/wp\/v2\/media\/1737"}],"wp:attachment":[{"href":"https:\/\/www.ufmg.br\/pginovacaotecnologica\/index.php\/wp-json\/wp\/v2\/media?parent=1735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ufmg.br\/pginovacaotecnologica\/index.php\/wp-json\/wp\/v2\/categories?post=1735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ufmg.br\/pginovacaotecnologica\/index.php\/wp-json\/wp\/v2\/tags?post=1735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}