{"id":4461,"date":"2026-03-30T15:21:34","date_gmt":"2026-03-30T18:21:34","guid":{"rendered":"https:\/\/www.ufmg.br\/rededemuseus\/servicos\/?post_type=tnc_col_3474_item&#038;p=4461"},"modified":"2026-04-08T14:53:33","modified_gmt":"2026-04-08T17:53:33","slug":"viveiro-de-mudas","status":"publish","type":"tnc_col_3474_item","link":"https:\/\/www.ufmg.br\/rededemuseus\/servicos\/agenda\/viveiro-de-mudas\/","title":{"rendered":"Viveiro de Mudas"},"content":{"rendered":"<p>O Viveiro de mudas do Museu de Hist\u00f3ria Natural e Jardim Bot\u00e2nico da UFMG cultiva mudas de diferentes esp\u00e9cies arb\u00f3reas coletadas na pr\u00f3pria reserva.<\/p>\n<p>O setor realiza todo o processo para produ\u00e7\u00e3o de mudas de Mata atl\u00e2ntica, que  inclui a coleta de sementes,  sele\u00e7\u00e3o, beneficiamento, preparo de leito de enraizamento, manuten\u00e7\u00e3o, transplante e disponibiliza\u00e7\u00e3o para plantio da \u00e1rea.<\/p>\n<p>O objetivo do viveiro  \u00e9 a produ\u00e7\u00e3o de mudas com vistas ao enriquecimento e manuten\u00e7\u00e3o da reserva florestal da institui\u00e7\u00e3o, sendo o excedente disponibilizado para venda ao p\u00fablico externo.<\/p>\n<p>A disponibiliza\u00e7\u00e3o de mudas, mediante o pagamento de taxas, \u00e9 orientada, com o fornecimento de informa\u00e7\u00f5es necess\u00e1rias ao cultivo.<\/p>\n","protected":false},"featured_media":7046,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","class_list":["post-4461","tnc_col_3474_item","type-tnc_col_3474_item","status-publish","format-standard","has-post-thumbnail","hentry","tainacan-item-single-page"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/www.ufmg.br\/rededemuseus\/servicos\/wp-json\/wp\/v2\/tnc_col_3474_item\/4461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ufmg.br\/rededemuseus\/servicos\/wp-json\/wp\/v2\/tnc_col_3474_item"}],"about":[{"href":"https:\/\/www.ufmg.br\/rededemuseus\/servicos\/wp-json\/wp\/v2\/types\/tnc_col_3474_item"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ufmg.br\/rededemuseus\/servicos\/wp-json\/wp\/v2\/comments?post=4461"}],"version-history":[{"count":4,"href":"https:\/\/www.ufmg.br\/rededemuseus\/servicos\/wp-json\/wp\/v2\/tnc_col_3474_item\/4461\/revisions"}],"predecessor-version":[{"id":8887,"href":"https:\/\/www.ufmg.br\/rededemuseus\/servicos\/wp-json\/wp\/v2\/tnc_col_3474_item\/4461\/revisions\/8887"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ufmg.br\/rededemuseus\/servicos\/wp-json\/wp\/v2\/media\/7046"}],"wp:attachment":[{"href":"https:\/\/www.ufmg.br\/rededemuseus\/servicos\/wp-json\/wp\/v2\/media?parent=4461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}