{"id":6362,"date":"2026-03-23T10:44:05","date_gmt":"2026-03-23T13:44:05","guid":{"rendered":"https:\/\/www.ufmg.br\/sisu\/?page_id=6362"},"modified":"2026-04-10T15:41:00","modified_gmt":"2026-04-10T18:41:00","slug":"6a-chamada-da-lista-de-espera-sisu-ufmg-2026","status":"publish","type":"page","link":"https:\/\/www.ufmg.br\/sisu\/6a-chamada-da-lista-de-espera-sisu-ufmg-2026\/","title":{"rendered":"6\u00aa Chamada da Lista de Espera &#8211; SISU\/UFMG 2026"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.ufmg.br\/sisu\/wp-content\/uploads\/2026\/04\/6a-Chamada-da-Lista-de-Espera-SISU-2026-Resultado-dos-Recursos.pdf\" data-type=\"URL\" data-id=\"https:\/\/www.ufmg.br\/sisu\/wp-content\/uploads\/2026\/04\/6a-Chamada-da-Lista-de-Espera-SISU-2026-Resultado-dos-Recursos.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Resultado dos recursos<\/a>.<\/p>\n\n\n\n<p><a rel=\"noreferrer noopener\" href=\"https:\/\/www.ufmg.br\/sisu\/instrucoes-para-interposicao-de-recurso-sisu-ufmg-2026-6a-chamada-da-lista-de-espera\/\" data-type=\"URL\" data-id=\"https:\/\/www.ufmg.br\/sisu\/instrucoes-para-interposicao-de-recurso-sisu-ufmg-2026-6a-chamada-da-lista-de-espera\/\" target=\"_blank\">Instru\u00e7\u00f5es para interposi\u00e7\u00e3o de recurso<\/a>.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.ufmg.br\/sisu\/wp-content\/uploads\/2026\/04\/Matriculas-Confirmadas-Ampla-Concorrencia-6a-Chamada-da-LEt.pdf\" data-type=\"URL\" data-id=\"https:\/\/www.ufmg.br\/sisu\/wp-content\/uploads\/2026\/04\/Matriculas-Confirmadas-Ampla-Concorrencia-6a-Chamada-da-LEt.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Matr\u00edculas confirmadas (Ampla concorr\u00eancia)<\/a>.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.ufmg.br\/sisu\/wp-content\/uploads\/2026\/04\/Matriculas-Indeferidas-Ampla-Concorrencia-6a-Chamada-da-LE.pdf\" data-type=\"URL\" data-id=\"https:\/\/www.ufmg.br\/sisu\/wp-content\/uploads\/2026\/04\/Matriculas-Indeferidas-Ampla-Concorrencia-6a-Chamada-da-LE.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Matr\u00edculas indeferidas (Ampla concorr\u00eancia)<\/a>.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.ufmg.br\/sisu\/wp-content\/uploads\/2026\/04\/Matriculas-Confirmadas-Reserva-de-vagas-6a-Chamada-da-LE.pdf\" data-type=\"URL\" data-id=\"https:\/\/www.ufmg.br\/sisu\/wp-content\/uploads\/2026\/04\/Matriculas-Confirmadas-Reserva-de-vagas-6a-Chamada-da-LE.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Matr\u00edculas confirmadas (Reserva de vagas)<\/a>.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.ufmg.br\/sisu\/wp-content\/uploads\/2026\/04\/Matriculas-Indeferidas-Reserva-de-vagas-6a-Chamada-da-LE.pdf\" data-type=\"URL\" data-id=\"https:\/\/www.ufmg.br\/sisu\/wp-content\/uploads\/2026\/04\/Matriculas-Indeferidas-Reserva-de-vagas-6a-Chamada-da-LE.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Matr\u00edculas indeferidas (Reserva de vagas)<\/a>.<\/p>\n\n\n\n<p><a rel=\"noreferrer noopener\" href=\"https:\/\/www.ufmg.br\/sisu\/escala-de-atendimento-do-procedimento-presencial-de-verificacao-e-validacao-de-pessoa-com-deficiencia-6a-chamada-da-lista-de-espera\/\" data-type=\"URL\" data-id=\"https:\/\/www.ufmg.br\/sisu\/escala-de-atendimento-do-procedimento-presencial-de-verificacao-e-validacao-de-pessoa-com-deficiencia-6a-chamada-da-lista-de-espera\/\" target=\"_blank\">Escala de atendimento dos procedimentos presenciais \u2013 Banca de Verifica\u00e7\u00e3o e Valida\u00e7\u00e3o de Pessoa com Defici\u00eancia<\/a>. <\/p>\n\n\n\n<p><a href=\"https:\/\/www.ufmg.br\/sisu\/escala-de-atendimento-do-procedimento-presencial-de-heteroidentificacao-6a-chamada-da-lista-de-espera\/\" data-type=\"URL\" data-id=\"https:\/\/www.ufmg.br\/sisu\/escala-de-atendimento-do-procedimento-presencial-de-heteroidentificacao-6a-chamada-da-lista-de-espera\/\" target=\"_blank\" rel=\"noreferrer noopener\">Escala de atendimento dos procedimentos presenciais \u2013 Banca de heteroidentifica\u00e7\u00e3o<\/a>. <\/p>\n\n\n\n<p><a href=\"https:\/\/www.ufmg.br\/sisu\/registro-academico-via-internet-com-upload-da-documentacao-obrigatoria-6a-chamada-da-lista-de-espera\/\" data-type=\"URL\" data-id=\"https:\/\/www.ufmg.br\/sisu\/registro-academico-via-internet-com-upload-da-documentacao-obrigatoria-6a-chamada-da-lista-de-espera\/\" target=\"_blank\" rel=\"noreferrer noopener\">Clique aqui para acessar o Registro Acad\u00eamico, via internet, com upload da documenta\u00e7\u00e3o obrigat\u00f3ria<\/a>.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.ufmg.br\/sisu\/wp-content\/uploads\/2026\/03\/Notas-maximas-e-minimas-1-3.pdf\" data-type=\"URL\" data-id=\"https:\/\/www.ufmg.br\/sisu\/wp-content\/uploads\/2026\/03\/Notas-maximas-e-minimas-1-3.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Pontua\u00e7\u00f5es m\u00ednimas e m\u00e1ximas<\/a>.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.ufmg.br\/sisu\/wp-content\/uploads\/2026\/03\/6a-Chamada-da-Lista-de-Espera-SISU-2026.pdf\" data-type=\"URL\" data-id=\"https:\/\/www.ufmg.br\/sisu\/wp-content\/uploads\/2026\/03\/6a-Chamada-da-Lista-de-Espera-SISU-2026.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Consulte aqui a rela\u00e7\u00e3o dos candidatos convocados<\/a>.<\/p>\n\n\n\n<p><a href=\"https:\/\/www.ufmg.br\/sisu\/instrucoes-aos-candidatos-convocados-na-6a-chamada-da-lista-de-espera-do-sisu-ufmg-2026\/\" data-type=\"URL\" data-id=\"https:\/\/www.ufmg.br\/sisu\/instrucoes-aos-candidatos-convocados-na-6a-chamada-da-lista-de-espera-do-sisu-ufmg-2026\/\" target=\"_blank\" rel=\"noreferrer noopener\">Instru\u00e7\u00f5es para os candidatos convocados<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Resultado dos recursos. Instru\u00e7\u00f5es para interposi\u00e7\u00e3o de recurso. Matr\u00edculas confirmadas (Ampla concorr\u00eancia). Matr\u00edculas indeferidas (Ampla concorr\u00eancia). Matr\u00edculas confirmadas (Reserva de vagas). Matr\u00edculas indeferidas (Reserva de vagas). Escala de atendimento dos procedimentos presenciais \u2013 Banca de Verifica\u00e7\u00e3o e Valida\u00e7\u00e3o de Pessoa com Defici\u00eancia. Escala de atendimento dos procedimentos presenciais \u2013 Banca de heteroidentifica\u00e7\u00e3o. Clique aqui para [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ufmg.br\/sisu\/wp-json\/wp\/v2\/pages\/6362"}],"collection":[{"href":"https:\/\/www.ufmg.br\/sisu\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ufmg.br\/sisu\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ufmg.br\/sisu\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ufmg.br\/sisu\/wp-json\/wp\/v2\/comments?post=6362"}],"version-history":[{"count":7,"href":"https:\/\/www.ufmg.br\/sisu\/wp-json\/wp\/v2\/pages\/6362\/revisions"}],"predecessor-version":[{"id":6458,"href":"https:\/\/www.ufmg.br\/sisu\/wp-json\/wp\/v2\/pages\/6362\/revisions\/6458"}],"wp:attachment":[{"href":"https:\/\/www.ufmg.br\/sisu\/wp-json\/wp\/v2\/media?parent=6362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}